{"id":27195,"date":"2023-11-30T02:53:25","date_gmt":"2023-11-30T02:53:25","guid":{"rendered":"https:\/\/nsfocusglobal.com\/?p=27195"},"modified":"2023-11-30T02:53:25","modified_gmt":"2023-11-30T02:53:25","slug":"o-que-e-phishing","status":"publish","type":"post","link":"https:\/\/nsfocusglobal.com\/pt-br\/o-que-e-phishing\/","title":{"rendered":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0"},"content":{"rendered":"\n<p>O mundo digital est\u00e1 constantemente sob amea\u00e7a de um dos mais perigosos golpes cibern\u00e9ticos: o phishing.&nbsp;<\/p>\n\n\n\n<p>Trata-se de uma <strong>t\u00e9cnica maliciosa utilizada por cibercriminosos para enganar usu\u00e1rios<\/strong> e obter informa\u00e7\u00f5es pessoais e sens\u00edveis.<\/p>\n\n\n\n<p>Vamos explorar o que \u00e9, como funciona e como se proteger desses ataques. Continue a leitura!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Phishing?&nbsp;<\/h2>\n\n\n\n<p>Phishing \u00e9 uma <strong>pr\u00e1tica maliciosa que envolve a tentativa de enganar pessoas para obter informa\u00e7\u00f5es confidenciais,<\/strong> como senhas e dados financeiros.<\/p>\n\n\n\n<p><strong>Leia tamb\u00e9m: <\/strong><a href=\"https:\/\/nsfocusglobal.com\/pt-br\/ameacas-virtuais\/\"><strong>Amea\u00e7as virtuais: Dicas para manter a seguran\u00e7a<\/strong><\/a><\/p>\n\n\n\n<p>Geralmente, <strong>ocorre por meio de e-mails, mensagens e sites falsos<\/strong> que se passam por marcas confi\u00e1veis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como o Phishing funciona?&nbsp;<\/h2>\n\n\n\n<p>Os ataques de phishing come\u00e7am normalmente com uma comunica\u00e7\u00e3o falsa, que pode ser um e-mail, mensagem de texto ou liga\u00e7\u00e3o, <strong>onde os criminosos se passam por institui\u00e7\u00f5es leg\u00edtimas<\/strong>, induzindo as v\u00edtimas a compartilhar informa\u00e7\u00f5es.<\/p>\n\n\n\n<p><strong>Saiba tamb\u00e9m: <\/strong><a href=\"https:\/\/nsfocusglobal.com\/pt-br\/privacidade-de-dados\/\"><strong>Privacidade de dados: como proteger a sua empresa?<\/strong><\/a><\/p>\n\n\n\n<p><strong>Os golpistas enviam mensagens persuasivas, <\/strong>que ao serem clicadas ou baixadas por meio de arquivos anexados, liberam acesso aos criminosos para dados pessoais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de ataques de phishing&nbsp;<\/h2>\n\n\n\n<p>Existem v\u00e1rios tipos de phishing, por isso, separamos uma lista com os principais. Conhe\u00e7a!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Spear phishing (ou Phishing de website)&nbsp;<\/h3>\n\n\n\n<p><strong>Muito utilizado, ele cria p\u00e1ginas falsas de empresas varejistas<\/strong>, oferecendo produtos em promo\u00e7\u00f5es extremamente atrativas.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Clone phishing&nbsp;<\/h3>\n\n\n\n<p><strong>Cria e-mails duplicados de fontes confi\u00e1veis<\/strong>, induzindo os usu\u00e1rios a revelarem informa\u00e7\u00f5es pessoais. Tamb\u00e9m \u00e9 comum encontrar r\u00e9plicas exatas de sites leg\u00edtimos para roubar informa\u00e7\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">419\/scams nigerianos&nbsp;<\/h3>\n\n\n\n<p><strong>S\u00e3o promessas falsas de grandes recompensas financeiras em troca de informa\u00e7\u00f5es<\/strong> ou pagamentos, normalmente enviadas por e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Phone phishing&nbsp;<\/h3>\n\n\n\n<p>Ataques realizados por liga\u00e7\u00e3o, tamb\u00e9m com o objetivo de obter informa\u00e7\u00f5es confidenciais. <strong>Os criminosos tamb\u00e9m usam marcas respeitadas para enganar as v\u00edtimas.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como identificar um ataque de phishing?&nbsp;<\/h2>\n\n\n\n<p>Identificar esses ataques n\u00e3o \u00e9 uma tarefa muito dif\u00edcil. Por isso, fique <strong>atento a erros gramaticais, URLs suspeitos, e-mails n\u00e3o solicitados <\/strong>pedindo informa\u00e7\u00f5es confidenciais<strong> e promo\u00e7\u00f5es exageradas e inesperadas<\/strong>.<\/p>\n\n\n\n<p><strong>Leia mais: <\/strong><a href=\"https:\/\/nsfocusglobal.com\/pt-br\/o-que-e-um-firewall\/\"><strong>O que \u00e9 um Firewall e como escolher?<\/strong><\/a><\/p>\n\n\n\n<p>\u00c9 <strong>importante sempre verificar o remetente do e-mail, evitar clicar em links suspeitos<\/strong> e desconfiar de mensagens que voc\u00ea n\u00e3o solicitou contato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o perigo do phishing para as empresas?&nbsp;<\/h2>\n\n\n\n<p>Empresas podem sofrer grandes perdas financeiras, al\u00e9m de terem dados comprometidos e s\u00e9rios danos \u00e0 reputa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Conhe\u00e7a: <\/strong><a href=\"https:\/\/nsfocusglobal.com\/pt-br\/seguranca-de-rede\/\"><strong>Seguran\u00e7a de rede: o que \u00e9, solu\u00e7\u00f5es e para que serve?<\/strong><\/a><\/p>\n\n\n\n<p>Funcion\u00e1rios desinformados ou descuidados podem representar um risco significativo para a seguran\u00e7a dos dados corporativos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tem como remover o phishing?<\/h2>\n\n\n\n<p>Embora seja um desafio remov\u00ea-lo completamente, a conscientiza\u00e7\u00e3o e educa\u00e7\u00e3o sobre <a href=\"https:\/\/nsfocusglobal.com\/pt-br\/ciberseguranca-o-que-e-e-como-se-proteger-das-ameacas-virtuais\/\">seguran\u00e7a cibern\u00e9tica<\/a> podem ajudar a mitigar os riscos.<\/p>\n\n\n\n<p>Por isso, depois de um ataque, \u00e9 fundamental tomar as medidas imediatas para minimizar danos, o que inclui alterar todas as senhas, notificar as autoridades respons\u00e1veis e implementar medidas de seguran\u00e7a mais rigorosas.<\/p>\n\n\n\n<p><strong>Veja tamb\u00e9m: <a href=\"https:\/\/nsfocusglobal.com\/pt-br\/o-que-e-xdr\/\" target=\"_blank\" rel=\"noreferrer noopener\">O que \u00e9 XDR?<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como denunciar?<\/h2>\n\n\n\n<p>Sim, \u00e9 poss\u00edvel! Se voc\u00ea suspeita ter encontrado uma p\u00e1gina falsa, <a href=\"https:\/\/safebrowsing.google.com\/safebrowsing\/report_phish\/?hl=pt-BR\">preencha aqui<\/a> o formul\u00e1rio para fazer a den\u00fancia \u00e0 equipe de Navega\u00e7\u00e3o Segura do Google.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dicas para se proteger de ataques phishing&nbsp;<\/h2>\n\n\n\n<p>Fique por dentro e saiba como passar longe desse tipo de amea\u00e7a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Verifique a legitimidade dos remetentes antes de clicar em links ou fornecer informa\u00e7\u00f5es;<\/li>\n\n\n\n<li>N\u00e3o compartilhe informa\u00e7\u00f5es pessoais ou financeiras atrav\u00e9s de e-mails n\u00e3o solicitados;<\/li>\n\n\n\n<li>Mantenha seu software e antiv\u00edrus atualizados;<\/li>\n\n\n\n<li>Realize treinamentos regulares para educar funcion\u00e1rios sobre pr\u00e1ticas seguras na Internet;<\/li>\n\n\n\n<li>Mantenha boas solu\u00e7\u00f5es de seguran\u00e7a para mitigar os ataques.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Leia tamb\u00e9m: <a href=\"https:\/\/nsfocusglobal.com\/pt-br\/solucao-anti-ddos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Solu\u00e7\u00e3o Anti-DDoS: o que \u00e9 e como funciona essa prote\u00e7\u00e3o?<\/a><\/strong><\/p>\n\n\n\n<p>A NSFOCUS, refer\u00eancia global em ciberseguran\u00e7a e solu\u00e7\u00f5es contra ataques cibern\u00e9ticos, possui em seu portf\u00f3lio quatro produtos focados em <a href=\"https:\/\/nsfocusglobal.com\/pt-br\/continuous-threat-exposure-management\/\">combater phishing e na gest\u00e3o de amea\u00e7as cont\u00ednuas<\/a> (CTEM).<br>Por isso, caso ainda n\u00e3o tenha ou n\u00e3o esteja satisfeito com a sua solu\u00e7\u00e3o atual, n\u00e3o perca tempo e <a href=\"https:\/\/nsfocusglobal.com\/pt-br\/fale-conosco\/\">entre em contato<\/a> agora mesmo para saber qual \u00e9 a melhor op\u00e7\u00e3o para sua empresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mundo digital est\u00e1 constantemente sob amea\u00e7a de um dos mais perigosos golpes cibern\u00e9ticos: o phishing.&nbsp; Trata-se de uma t\u00e9cnica maliciosa utilizada por cibercriminosos para enganar usu\u00e1rios e obter informa\u00e7\u00f5es pessoais e sens\u00edveis. Vamos explorar o que \u00e9, como funciona e como se proteger desses ataques. Continue a leitura! O que \u00e9 Phishing?&nbsp; Phishing \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[808],"tags":[],"class_list":["post-27195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0<\/title>\n<meta name=\"description\" content=\"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0\" \/>\n<meta property=\"og:description\" content=\"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/\" \/>\n<meta property=\"og:site_name\" content=\"NSFOCUS\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T02:53:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg\" \/>\n<meta name=\"author\" content=\"NSFOCUS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0\" \/>\n<meta name=\"twitter:description\" content=\"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NSFOCUS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/\"},\"author\":{\"name\":\"NSFOCUS\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#\\\/schema\\\/person\\\/fd9ab61c9c77a81bbd870f725cc0c61d\"},\"headline\":\"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0\",\"datePublished\":\"2023-11-30T02:53:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/\"},\"wordCount\":731,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nsfocusglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/phishing.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/\",\"url\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/\",\"name\":\"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nsfocusglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/phishing.jpg\",\"datePublished\":\"2023-11-30T02:53:25+00:00\",\"description\":\"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nsfocusglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/phishing.jpg\",\"contentUrl\":\"https:\\\/\\\/nsfocusglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/phishing.jpg\",\"width\":328,\"height\":225,\"caption\":\"Uma imagem que ilustra o que \u00e9 phishing.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/o-que-e-phishing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nsfocusglobal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#website\",\"url\":\"https:\\\/\\\/nsfocusglobal.com\\\/\",\"name\":\"NSFOCUS\",\"description\":\"Security Made Smart and Simple\",\"publisher\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nsfocusglobal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#organization\",\"name\":\"NSFOCUS\",\"url\":\"https:\\\/\\\/nsfocusglobal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nsfocusglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-ns.png\",\"contentUrl\":\"https:\\\/\\\/nsfocusglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-ns.png\",\"width\":248,\"height\":36,\"caption\":\"NSFOCUS\"},\"image\":{\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nsfocusglobal.com\\\/#\\\/schema\\\/person\\\/fd9ab61c9c77a81bbd870f725cc0c61d\",\"name\":\"NSFOCUS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3dc987908fc59791d261b1006d84eb931d15287261476b9384e690ed0c568de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3dc987908fc59791d261b1006d84eb931d15287261476b9384e690ed0c568de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3dc987908fc59791d261b1006d84eb931d15287261476b9384e690ed0c568de?s=96&d=mm&r=g\",\"caption\":\"NSFOCUS\"},\"sameAs\":[\"https:\\\/\\\/nsfocusglobal.com\"],\"url\":\"https:\\\/\\\/nsfocusglobal.com\\\/pt-br\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0","description":"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0","og_description":"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.","og_url":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/","og_site_name":"NSFOCUS","article_published_time":"2023-11-30T02:53:25+00:00","og_image":[{"url":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg","type":"","width":"","height":""}],"author":"NSFOCUS","twitter_card":"summary_large_image","twitter_title":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0","twitter_description":"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.","twitter_image":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg","twitter_misc":{"Escrito por":"NSFOCUS","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#article","isPartOf":{"@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/"},"author":{"name":"NSFOCUS","@id":"https:\/\/nsfocusglobal.com\/#\/schema\/person\/fd9ab61c9c77a81bbd870f725cc0c61d"},"headline":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0","datePublished":"2023-11-30T02:53:25+00:00","mainEntityOfPage":{"@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/"},"wordCount":731,"commentCount":0,"publisher":{"@id":"https:\/\/nsfocusglobal.com\/#organization"},"image":{"@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#primaryimage"},"thumbnailUrl":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg","articleSection":["Blog"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/","url":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/","name":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0","isPartOf":{"@id":"https:\/\/nsfocusglobal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#primaryimage"},"image":{"@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#primaryimage"},"thumbnailUrl":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg","datePublished":"2023-11-30T02:53:25+00:00","description":"Descubra o que \u00e9 phishing, os tipos de ataques mais comuns e as melhores dicas para manter os neg\u00f3cios protegidos.","breadcrumb":{"@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nsfocusglobal.com\/o-que-e-phishing\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#primaryimage","url":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg","contentUrl":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2023\/11\/phishing.jpg","width":328,"height":225,"caption":"Uma imagem que ilustra o que \u00e9 phishing."},{"@type":"BreadcrumbList","@id":"https:\/\/nsfocusglobal.com\/o-que-e-phishing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nsfocusglobal.com\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 Phishing? Tipos e dicas para evitar golpes\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/nsfocusglobal.com\/#website","url":"https:\/\/nsfocusglobal.com\/","name":"NSFOCUS","description":"Security Made Smart and Simple","publisher":{"@id":"https:\/\/nsfocusglobal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nsfocusglobal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nsfocusglobal.com\/#organization","name":"NSFOCUS","url":"https:\/\/nsfocusglobal.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nsfocusglobal.com\/#\/schema\/logo\/image\/","url":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2024\/08\/logo-ns.png","contentUrl":"https:\/\/nsfocusglobal.com\/wp-content\/uploads\/2024\/08\/logo-ns.png","width":248,"height":36,"caption":"NSFOCUS"},"image":{"@id":"https:\/\/nsfocusglobal.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nsfocusglobal.com\/#\/schema\/person\/fd9ab61c9c77a81bbd870f725cc0c61d","name":"NSFOCUS","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d3dc987908fc59791d261b1006d84eb931d15287261476b9384e690ed0c568de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3dc987908fc59791d261b1006d84eb931d15287261476b9384e690ed0c568de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3dc987908fc59791d261b1006d84eb931d15287261476b9384e690ed0c568de?s=96&d=mm&r=g","caption":"NSFOCUS"},"sameAs":["https:\/\/nsfocusglobal.com"],"url":"https:\/\/nsfocusglobal.com\/pt-br\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/posts\/27195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/comments?post=27195"}],"version-history":[{"count":0,"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/posts\/27195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/media\/27196"}],"wp:attachment":[{"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/media?parent=27195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/categories?post=27195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nsfocusglobal.com\/pt-br\/wp-json\/wp\/v2\/tags?post=27195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}